{"id":117,"date":"2025-03-05T11:02:55","date_gmt":"2025-03-05T10:02:55","guid":{"rendered":"http:\/\/31.31.73.222\/slunecnyapartmanlosiny_com\/?page_id=117"},"modified":"2025-04-08T10:01:50","modified_gmt":"2025-04-08T08:01:50","slug":"beschreibung-der-wohnung","status":"publish","type":"page","link":"https:\/\/slunecnyapartmanlosiny.com\/de\/beschreibung-der-wohnung\/","title":{"rendered":"Beschreibung der Wohnung"},"content":{"rendered":"\n<div class=\"wp-block-columns alignwide is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"915\" src=\"https:\/\/slunecnyapartmanlosiny.com\/wp-content\/uploads\/2025\/03\/IMG-20240331-WA0003-1-1024x915.webp\" alt=\"\" class=\"wp-image-358\" srcset=\"https:\/\/slunecnyapartmanlosiny.com\/wp-content\/uploads\/2025\/03\/IMG-20240331-WA0003-1-1024x915.webp 1024w, https:\/\/slunecnyapartmanlosiny.com\/wp-content\/uploads\/2025\/03\/IMG-20240331-WA0003-1-300x268.webp 300w, https:\/\/slunecnyapartmanlosiny.com\/wp-content\/uploads\/2025\/03\/IMG-20240331-WA0003-1-768x686.webp 768w, https:\/\/slunecnyapartmanlosiny.com\/wp-content\/uploads\/2025\/03\/IMG-20240331-WA0003-1-1536x1373.webp 1536w, https:\/\/slunecnyapartmanlosiny.com\/wp-content\/uploads\/2025\/03\/IMG-20240331-WA0003-1-1568x1401.webp 1568w, https:\/\/slunecnyapartmanlosiny.com\/wp-content\/uploads\/2025\/03\/IMG-20240331-WA0003-1.webp 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Das Sunny Apartment ist f\u00fcr bis zu 6 Personen ausgelegt, idealerweise 4 Erwachsene und 2 Kinder.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es verf\u00fcgt \u00fcber zwei Schlafzimmer (jeweils mit einem Doppelbett, eines davon zus\u00e4tzlich mit einem Etagenbett), eine voll ausgestattete K\u00fcche (K\u00fchlschrank, Mikrowelle, Backofen, Kaffeemaschine, Toaster, Induktionsherd \u2026), ein luxuri\u00f6ses Badezimmer, eine Terrasse und direkten Zugang zum Garten.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es eignet sich perfekt f\u00fcr Eltern mit Kindern sowie f\u00fcr Familien mit Gro\u00dfeltern, Eltern und Kindern. Die Gro\u00dfeltern k\u00f6nnen aktiv mit ihren Enkeln spielen, w\u00e4hrend die Eltern die Skipisten, den Wellnessbereich usw. genie\u00dfen.<br>Dieses Apartment ist auch ideal f\u00fcr eine Gruppe von Freunden, die Outdoor-Aktivit\u00e4ten nachgehen oder einfach nur entspannen m\u00f6chten.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Jedes Schlafzimmer verf\u00fcgt \u00fcber einen Fernseher und WLAN ist ebenfalls verf\u00fcgbar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Im Garten des Sunny Apartments gibt es eine private Feuerstelle und einen Grillplatz im Freien, Sitzgelegenheiten sowie einen privaten Spielplatz f\u00fcr Kinder.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hunde sind bei uns willkommen.<\/p>\n<\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Das Sunny Apartment ist f\u00fcr bis zu 6 Personen ausgelegt, idealerweise 4 Erwachsene und 2 Kinder. Es verf\u00fcgt \u00fcber zwei Schlafzimmer (jeweils mit einem Doppelbett, eines davon zus\u00e4tzlich mit einem Etagenbett), eine voll ausgestattete K\u00fcche (K\u00fchlschrank, Mikrowelle, Backofen, Kaffeemaschine, Toaster, Induktionsherd \u2026), ein luxuri\u00f6ses Badezimmer, eine Terrasse und direkten Zugang zum Garten. Es eignet sich&hellip; <a class=\"more-link\" href=\"https:\/\/slunecnyapartmanlosiny.com\/de\/beschreibung-der-wohnung\/\"><span class=\"screen-reader-text\">Beschreibung der Wohnung<\/span> weiterlesen<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-117","page","type-page","status-publish","hentry","entry"],"_links":{"self":[{"href":"https:\/\/slunecnyapartmanlosiny.com\/de\/wp-json\/wp\/v2\/pages\/117","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/slunecnyapartmanlosiny.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/slunecnyapartmanlosiny.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/slunecnyapartmanlosiny.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/slunecnyapartmanlosiny.com\/de\/wp-json\/wp\/v2\/comments?post=117"}],"version-history":[{"count":4,"href":"https:\/\/slunecnyapartmanlosiny.com\/de\/wp-json\/wp\/v2\/pages\/117\/revisions"}],"predecessor-version":[{"id":505,"href":"https:\/\/slunecnyapartmanlosiny.com\/de\/wp-json\/wp\/v2\/pages\/117\/revisions\/505"}],"wp:attachment":[{"href":"https:\/\/slunecnyapartmanlosiny.com\/de\/wp-json\/wp\/v2\/media?parent=117"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}